{"id":73,"count":3,"description":"","link":"https:\/\/digital-pinball.com\/es\/product-category\/full-size\/","name":"Tama\u00f1o completo","slug":"full-size","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/digital-pinball.com\/es\/wp-json\/wp\/v2\/product_cat\/73","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digital-pinball.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/digital-pinball.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/digital-pinball.com\/es\/wp-json\/wp\/v2\/product?product_cat=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}